{"id":8787,"date":"2022-09-11T12:13:14","date_gmt":"2022-09-11T10:13:14","guid":{"rendered":"https:\/\/footballretroshirts.com\/lecce"},"modified":"2022-09-11T12:13:14","modified_gmt":"2022-09-11T10:13:14","slug":"lecce","status":"publish","type":"page","link":"https:\/\/footballretroshirts.com\/pt-pt\/clubes\/italia\/lecce","title":{"rendered":"Lecce"},"content":{"rendered":"<h1>cl\u00e1ssico e retr\u00f4 camisola a partir de Lecce<\/h1>\n<p>aqui voc\u00ea encontrar\u00e1 \u00f3timos camisas cl\u00e1ssicas e retr\u00f4 de Lecce. Lecce \u00e9 um clube de 1908 que jogando suas partidas em casa em Stadio Comunale Via del Mare Viale dello Stadio, Lecce. o est\u00e1dio pode casas 33876 espectadores. esperamos que voc\u00ea encontre o grande blusas retr\u00f4 de Lecce voc\u00ea est\u00e1 procurando.<\/p>\n<p><a href=\"https:\/\/www.classicfootballshirts.co.uk\/nsearch\/?q=Lecce\">clique aqui para encontrar o seu retr\u00f4 Lecce camisola<\/a><\/p>\n<p><strong>Est\u00e1dio: <\/strong>Stadio Comunale Via del Mare<br \/>\n<strong>Capacidade: <\/strong>33876<br \/>\n<strong>Endere\u00e7o: <\/strong>Viale dello Stadio, Lecce<br \/>\n<strong>Fundado: <\/strong>1908<\/p>\n","protected":false},"excerpt":{"rendered":"<p>cl\u00e1ssico e retr\u00f4 camisola a partir de Lecce aqui voc\u00ea encontrar\u00e1 \u00f3timos camisas cl\u00e1ssicas e retr\u00f4 de Lecce. Lecce \u00e9 um clube de 1908 que jogando suas partidas em casa em Stadio Comunale Via del Mare Viale dello Stadio, Lecce. o est\u00e1dio pode casas 33876 espectadores. esperamos que voc\u00ea encontre o grande blusas retr\u00f4 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8754,"parent":3049,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"voc\u00ea est\u00e1 procurando um novo retr\u00f4 Lecce camisola? olhe mais nu\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footballretroshirts.com\/pt-pt\/lecce\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"retr\u00f4 Lecce camisola. encontre delicioso cl\u00e1ssico Lecce camisola aqui\" \/>\n<meta property=\"og:description\" content=\"voc\u00ea est\u00e1 procurando um novo retr\u00f4 Lecce camisola? olhe mais nu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footballretroshirts.com\/pt-pt\/lecce\" \/>\n<meta property=\"og:site_name\" content=\"Retro football shirts\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footballretroshirts.com\/wp-content\/uploads\/2022\/09\/867.png\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footballretroshirts.com\/en\/#website\",\"url\":\"https:\/\/footballretroshirts.com\/en\/\",\"name\":\"Retro football shirts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footballretroshirts.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/footballretroshirts.com\/pt-pt\/lecce#primaryimage\",\"inLanguage\":\"pt-PT\",\"url\":\"https:\/\/footballretroshirts.com\/wp-content\/uploads\/2022\/09\/867.png\",\"contentUrl\":\"https:\/\/footballretroshirts.com\/wp-content\/uploads\/2022\/09\/867.png\",\"width\":150,\"height\":150},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footballretroshirts.com\/pt-pt\/lecce#webpage\",\"url\":\"https:\/\/footballretroshirts.com\/pt-pt\/lecce\",\"name\":\"retr\\u00f4 Lecce camisola. encontre delicioso cl\\u00e1ssico Lecce camisola aqui\",\"isPartOf\":{\"@id\":\"https:\/\/footballretroshirts.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/footballretroshirts.com\/pt-pt\/lecce#primaryimage\"},\"datePublished\":\"2022-09-11T10:13:14+00:00\",\"dateModified\":\"2022-09-11T10:13:14+00:00\",\"description\":\"voc\\u00ea est\\u00e1 procurando um novo retr\\u00f4 Lecce camisola? olhe mais nu\",\"breadcrumb\":{\"@id\":\"https:\/\/footballretroshirts.com\/pt-pt\/lecce#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footballretroshirts.com\/pt-pt\/lecce\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footballretroshirts.com\/pt-pt\/lecce#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lecce\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"description":"voc\u00ea est\u00e1 procurando um novo retr\u00f4 Lecce camisola? olhe mais nu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footballretroshirts.com\/pt-pt\/lecce","og_locale":"pt_PT","og_type":"article","og_title":"retr\u00f4 Lecce camisola. encontre delicioso cl\u00e1ssico Lecce camisola aqui","og_description":"voc\u00ea est\u00e1 procurando um novo retr\u00f4 Lecce camisola? olhe mais nu","og_url":"https:\/\/footballretroshirts.com\/pt-pt\/lecce","og_site_name":"Retro football shirts","og_image":[{"width":150,"height":150,"filesize":18782,"url":"https:\/\/footballretroshirts.com\/wp-content\/uploads\/2022\/09\/867.png","path":"\/var\/www\/footballretroshirts.com\/public_html\/wp-content\/uploads\/2022\/09\/867.png","size":"full","id":8754,"alt":"","pixels":22500,"type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/footballretroshirts.com\/en\/#website","url":"https:\/\/footballretroshirts.com\/en\/","name":"Retro football shirts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footballretroshirts.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"ImageObject","@id":"https:\/\/footballretroshirts.com\/pt-pt\/lecce#primaryimage","inLanguage":"pt-PT","url":"https:\/\/footballretroshirts.com\/wp-content\/uploads\/2022\/09\/867.png","contentUrl":"https:\/\/footballretroshirts.com\/wp-content\/uploads\/2022\/09\/867.png","width":150,"height":150},{"@type":"WebPage","@id":"https:\/\/footballretroshirts.com\/pt-pt\/lecce#webpage","url":"https:\/\/footballretroshirts.com\/pt-pt\/lecce","name":"retr\u00f4 Lecce camisola. encontre delicioso cl\u00e1ssico Lecce camisola aqui","isPartOf":{"@id":"https:\/\/footballretroshirts.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/footballretroshirts.com\/pt-pt\/lecce#primaryimage"},"datePublished":"2022-09-11T10:13:14+00:00","dateModified":"2022-09-11T10:13:14+00:00","description":"voc\u00ea est\u00e1 procurando um novo retr\u00f4 Lecce camisola? olhe mais nu","breadcrumb":{"@id":"https:\/\/footballretroshirts.com\/pt-pt\/lecce#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footballretroshirts.com\/pt-pt\/lecce"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footballretroshirts.com\/pt-pt\/lecce#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lecce"}]}]}},"_links":{"self":[{"href":"https:\/\/footballretroshirts.com\/pt-pt\/wp-json\/wp\/v2\/pages\/8787"}],"collection":[{"href":"https:\/\/footballretroshirts.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/footballretroshirts.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/footballretroshirts.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footballretroshirts.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=8787"}],"version-history":[{"count":0,"href":"https:\/\/footballretroshirts.com\/pt-pt\/wp-json\/wp\/v2\/pages\/8787\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/footballretroshirts.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footballretroshirts.com\/pt-pt\/wp-json\/wp\/v2\/media\/8754"}],"wp:attachment":[{"href":"https:\/\/footballretroshirts.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=8787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}